{"id":96,"count":161,"description":"","link":"https:\/\/ckddiz.cz\/blog\/category\/technologie\/","name":"Technologie","slug":"technologie","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Technologie Archivy - ckddiz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ckddiz.cz\/blog\/category\/technologie\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Technologie Archivy - ckddiz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ckddiz.cz\/blog\/category\/technologie\/\" \/>\n<meta property=\"og:site_name\" content=\"ckddiz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/ckddiz.cz\/blog\/category\/technologie\/\",\"url\":\"https:\/\/ckddiz.cz\/blog\/category\/technologie\/\",\"name\":\"Technologie Archivy - ckddiz\",\"isPartOf\":{\"@id\":\"https:\/\/ckddiz.cz\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/ckddiz.cz\/blog\/category\/technologie\/#breadcrumb\"},\"inLanguage\":\"cs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ckddiz.cz\/blog\/category\/technologie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\/\/ckddiz.cz\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Technologie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ckddiz.cz\/blog\/#website\",\"url\":\"https:\/\/ckddiz.cz\/blog\/\",\"name\":\"ckddiz\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/ckddiz.cz\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ckddiz.cz\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ckddiz.cz\/blog\/#organization\",\"name\":\"ckddiz\",\"url\":\"https:\/\/ckddiz.cz\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\/\/ckddiz.cz\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ckddiz.cz\/blog\/wp-content\/uploads\/2025\/06\/ckddiz-logo.jpg\",\"contentUrl\":\"https:\/\/ckddiz.cz\/blog\/wp-content\/uploads\/2025\/06\/ckddiz-logo.jpg\",\"width\":2048,\"height\":2048,\"caption\":\"ckddiz\"},\"image\":{\"@id\":\"https:\/\/ckddiz.cz\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Technologie Archivy - ckddiz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ckddiz.cz\/blog\/category\/technologie\/","og_locale":"cs_CZ","og_type":"article","og_title":"Technologie Archivy - ckddiz","og_url":"https:\/\/ckddiz.cz\/blog\/category\/technologie\/","og_site_name":"ckddiz","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ckddiz.cz\/blog\/category\/technologie\/","url":"https:\/\/ckddiz.cz\/blog\/category\/technologie\/","name":"Technologie Archivy - ckddiz","isPartOf":{"@id":"https:\/\/ckddiz.cz\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/ckddiz.cz\/blog\/category\/technologie\/#breadcrumb"},"inLanguage":"cs"},{"@type":"BreadcrumbList","@id":"https:\/\/ckddiz.cz\/blog\/category\/technologie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/ckddiz.cz\/blog\/"},{"@type":"ListItem","position":2,"name":"Technologie"}]},{"@type":"WebSite","@id":"https:\/\/ckddiz.cz\/blog\/#website","url":"https:\/\/ckddiz.cz\/blog\/","name":"ckddiz","description":"","publisher":{"@id":"https:\/\/ckddiz.cz\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ckddiz.cz\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/ckddiz.cz\/blog\/#organization","name":"ckddiz","url":"https:\/\/ckddiz.cz\/blog\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/ckddiz.cz\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ckddiz.cz\/blog\/wp-content\/uploads\/2025\/06\/ckddiz-logo.jpg","contentUrl":"https:\/\/ckddiz.cz\/blog\/wp-content\/uploads\/2025\/06\/ckddiz-logo.jpg","width":2048,"height":2048,"caption":"ckddiz"},"image":{"@id":"https:\/\/ckddiz.cz\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ckddiz.cz\/blog\/wp-json\/wp\/v2\/categories\/96","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ckddiz.cz\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/ckddiz.cz\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/ckddiz.cz\/blog\/wp-json\/wp\/v2\/posts?categories=96"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}